{"id":6012,"date":"2018-03-19T13:43:36","date_gmt":"2018-03-19T12:43:36","guid":{"rendered":"https:\/\/www3.unifr.ch\/alma-georges?p=6012"},"modified":"2018-03-20T08:24:55","modified_gmt":"2018-03-20T07:24:55","slug":"je-voulais-sortir-de-ma-zone-de-confort","status":"publish","type":"post","link":"https:\/\/www.unifr.ch\/alma-georges\/articles\/2018\/je-voulais-sortir-de-ma-zone-de-confort?lang=de","title":{"rendered":"\u00abJe voulais sortir de ma zone de confort\u00bb"},"content":{"rendered":"<h4><strong>Organis\u00e9s par et pour les \u00e9tudiants, du 26 au 29 mars prochains \u00e0 l\u2019Universit\u00e9 de Fribourg, les Career days proposent un lien avec le monde professionnel. Rencontre avec Rapha\u00eblle Borgeaud, responsable de cet \u00e9v\u00e9nement chapeaut\u00e9 par l\u2019Association internationale des \u00e9tudiants en sciences \u00e9conomiques et commerciales (AIESEC).\u00a0<\/strong><\/h4>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p>\u00abOn est plus ou moins pr\u00eat.\u00bb A quelques jours des Career days, Rapha\u00eblle Borgeaud balance entre enthousiasme et appr\u00e9hension. Mises sur pied chaque ann\u00e9e par l\u2019Association internationale des \u00e9tudiants en sciences \u00e9conomiques et commerciales (AIESEC), ces journ\u00e9es permettent d\u2019\u00e9tablir \u00abun pont entre les \u00e9tudiants et les entreprises\u00bb, explique cette \u00e9tudiante de 23 ans, responsable de cet \u00e9v\u00e9nement, alors qu\u2019elle r\u00e9alise un Master en business communication \u00e0 l\u2019Universit\u00e9 de Fribourg. L\u2019un de ses mod\u00e8les dans la vie? L\u2019actrice Emma Watson. Pas seulement, parce qu\u2019elle fait partie de son enfance avec <em>Harry Potter<\/em>, mais aussi parce qu\u2019elle a poursuivi ses \u00e9tudes et s\u2019engage pour la cause de femmes. \u00abJ\u2019admire les jeunes qui s\u2019engagent pour des causes.\u00bb<\/p>\n<p>Du lundi\u00a026 au jeudi 29 mars, sur le site de P\u00e9rolles\u00a0II, plusieurs soci\u00e9t\u00e9s se pr\u00e9senteront par le biais de diff\u00e9rents <em>workshops<\/em>. \u00abLes entreprises pr\u00e9sentes vont de PwC \u00e0 Swiss medical Network, en passant par la Vaudoise assurance, ainsi que des structures comme Fri-up et Jeunes@work, ou encore des cabinets d\u2019avocats\u00bb, pr\u00e9cise l\u2019organisatrice. Le mercredi 28 mars, de 10h \u00e0 17h, une dizaine d\u2019organismes et d\u2019entreprises tiendront \u00e9galement des stands dans le couloir principal. Si l\u2019\u00e9v\u00e9nement s\u2019organise sur le m\u00eame mode \u00e0 Zurich et Lausanne, Fribourg a aussi int\u00e9gr\u00e9 les Law days, sp\u00e9cifiques au domaine juridique, avec plusieurs ateliers sur le site de Mis\u00e9ricorde. Les inscriptions aux <em>workshops<\/em> peuvent se faire via le site <a href=\"https:\/\/careerdays.ch\" target=\"_blank\" rel=\"noopener\">careerdays.ch<\/a>.<\/p>\n<p><strong>Un travail d\u2019\u00e9quipe<br \/>\n<\/strong>C\u2019est peu dire que Rapha\u00eblle Borgeaud a l\u2019engagement chevill\u00e9 au corps. De Morges, o\u00f9 elle a grandi, elle part d\u2019abord pour Lugano pour un Bachelor en sciences de la communication. L\u00e0, elle int\u00e8gre l\u2019AIESEC, association pr\u00e9sente dans plus de 120 pays, qui vise \u00e0 promouvoir le <em>leadership<\/em> chez les jeunes, notamment par le biais de stages \u00e0 l\u2019\u00e9tranger et d\u2019actions de volontariat. La mise sur pieds des Career days participe de cet esprit. Au sein d\u2019une \u00e9quipe de six \u00e9tudiants, elle se charge surtout de la coordination des op\u00e9rations. \u00abVendre un projet, contacter des entreprises par t\u00e9l\u00e9phone, prendre sur soi et ne pas \u00eatre trop sensible en cas de refus. Je voulais sortir de ma zone de confort et j\u2019ai appris \u00e9norm\u00e9ment\u00bb, t\u00e9moigne-t-elle, pr\u00e9cisant que toute l\u2019\u00e9quipe m\u00e8ne le projet parall\u00e8lement \u00e0 ses \u00e9tudes. \u00abOn fonctionne beaucoup par messages Whatsapp.\u00bb<\/p>\n<p>Rapha\u00eblle Borgeaud estime que les Career days repr\u00e9sentent une belle occasion pour les \u00e9tudiants. Elle souligne qu\u2019il s\u2019agit d\u2019un \u00e9v\u00e9nement de recrutement unique \u00e0 Fribourg. Donner de la visibilit\u00e9 \u00e0 l\u2019\u00e9v\u00e9nement est un aspect important, car elle observe que si, de mani\u00e8re g\u00e9n\u00e9rale, les \u00e9tudiants trouvent ce genre de journ\u00e9es int\u00e9ressant, \u00abbeaucoup ne se sentent souvent pas pr\u00eats \u00e0 saisir une opportunit\u00e9. Durant leur cursus, les \u00e9tudiants entrent d\u00e9j\u00e0 en contact avec les r\u00e9alit\u00e9s du monde professionnel, par exemple au travers des diff\u00e9rents jobs ou stages qu\u2019ils effectuent. Les Career days sont surtout utiles pour ceux qui sont \u00e0 la recherche d\u2019un \u2039vrai\u203a travail \u00e0 la fin de leurs \u00e9tudes.\u00bb<\/p>\n<p>Arriv\u00e9e l\u2019automne dernier \u00e0 Fribourg, Rapha\u00eblle Borgeaud cherche elle-m\u00eame d\u00e9j\u00e0 une place de stage. L\u00e0 encore, ses valeurs la portent. \u00abJ\u2019aimerais beaucoup faire un stage dans une ONG active dans un domaine important \u00e0 mes yeux, par exemple ce qui touche \u00e0 l\u2019\u00e9ducation ou au climat. C\u2019est d\u2019ailleurs l\u2019esprit d\u2019AIESEC, de nous rendre conscients du r\u00f4le que nous pouvons jouer dans la soci\u00e9t\u00e9\u00bb, dit-elle. En attendant, Rapha\u00eblle Borgeaud court d\u2019un mandat \u00e0 l\u2019autre, comme avec le festival de th\u00e9\u00e2tre des Granges, \u00e0 La Chaux, dans lequel elle s\u2019investit. Un rythme de marathonien loin d\u2019effrayer cette sportive, f\u00e9rue de tennis et de course \u00e0 pied. Parmi ses prochains d\u00e9fis justement? Les 20 kilom\u00e8tres de Lausanne. \u00abTout \u00e7a me stimule\u00a0! Ne faire qu\u2019\u00e9tudier ne me conviendrait pas.\u00bb<\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<span style=\"color: #ff6600;\">__________<\/span><\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<ul>\n<li><a href=\"https:\/\/agenda.unifr.ch\/e\/de\/2928\/\" target=\"_blank\" rel=\"noopener\">Contact<\/a> pour les Career days fribourgeoises<\/li>\n<li><a href=\"https:\/\/careerdays.ch\/\" target=\"_blank\" rel=\"noopener\">Site<\/a> des Career days<\/li>\n<li><a href=\"http:\/\/www.unifr.ch\/uni-info\/fr\/index\/associations\" target=\"_blank\" rel=\"noopener\">Groupe <\/a>Aiesec de l&rsquo;Unifr<\/li>\n<\/ul>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Organis\u00e9s par et pour les \u00e9tudiants, du 26 au 29 mars prochains \u00e0 l\u2019Universit\u00e9 de Fribourg, les Career days proposent un lien avec le monde professionnel. Rencontre avec Rapha\u00eblle Borgeaud, responsable de cet \u00e9v\u00e9nement chapeaut\u00e9 par l\u2019Association internationale des \u00e9tudiants en sciences \u00e9conomiques et commerciales (AIESEC).\u00a0 \u00abOn est plus ou moins pr\u00eat.\u00bb A quelques jours des Career days, Rapha\u00eblle Borgeaud balance entre enthousiasme et appr\u00e9hension. Mises sur pied chaque ann\u00e9e par l\u2019Association internationale des \u00e9tudiants en sciences \u00e9conomiques et commerciales (AIESEC), ces journ\u00e9es permettent d\u2019\u00e9tablir \u00abun pont entre les \u00e9tudiants et les entreprises\u00bb, explique cette \u00e9tudiante de 23 ans, responsable<\/p>\n","protected":false},"author":20,"featured_media":6010,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,113],"tags":[1098,1061,341,366],"_links":{"self":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/6012"}],"collection":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/comments?post=6012"}],"version-history":[{"count":1,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/6012\/revisions"}],"predecessor-version":[{"id":6013,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/6012\/revisions\/6013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media\/6010"}],"wp:attachment":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media?parent=6012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/categories?post=6012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/tags?post=6012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}