{"id":23421,"date":"2026-06-22T15:30:12","date_gmt":"2026-06-22T14:30:12","guid":{"rendered":"https:\/\/www.unifr.ch\/alma-georges?p=23421"},"modified":"2026-07-07T09:59:04","modified_gmt":"2026-07-07T08:59:04","slug":"fribourg-gotteron-un-club-qui-ne-sachete-pas-avec-de-largent","status":"publish","type":"post","link":"https:\/\/www.unifr.ch\/alma-georges\/articles\/2026\/fribourg-gotteron-un-club-qui-ne-sachete-pas-avec-de-largent","title":{"rendered":"Fribourg-Gott\u00e9ron: \u00abUn club qui ne s\u2019ach\u00e8te pas avec de l\u2019argent\u00bb"},"content":{"rendered":"<h4><strong>La soir\u00e9e d\u2019archives SportVintage proposait un retour par le son et l\u2019image sur l\u2019histoire du club de hockey fribourgeois. Point d\u2019orgue d\u2019une expo qui a attir\u00e9 2000\u00a0visiteurs et visiteuses durant tout le mois de mai.<\/strong><\/h4>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p>La temp\u00e9rature est mont\u00e9e d\u2019un cran, ce soir-l\u00e0, sous les poutres du dernier \u00e9tage de l\u2019Atelier \u00e0 Fribourg. Et pas seulement \u00e0 cause de la chaleur ext\u00e9rieure, mais aussi du fait des \u00e9motions ressenties par la centaine de personnes qui s\u2019y \u00e9tait r\u00e9unie. La raison? Le HC Fribourg-Gott\u00e9ron, encore une fois, \u00e9tait au centre de la soir\u00e9e. Ce mercredi 27 mai, le public assistait \u00e0 la soir\u00e9e SportVintage, une projection d\u2019archives audio et vid\u00e9o revenant sur l\u2019histoire de ce club devenu une marque qui tient de l\u2019appellation d\u2019origine contr\u00f4l\u00e9e dans le Canton.<\/p>\n<p>Cet \u00e9v\u00e9nement, co-organis\u00e9 par la Radio T\u00e9l\u00e9vision Suisse (RTS) et l\u2019Association pour la valorisation des archives et de l\u2019Histoire des sports (AvaHs), cl\u00f4turait l\u2019exposition \u00abDes Augustins \u00e0 Saint-L\u00e9onard. Le hockey sur glace \u00e0 Fribourg\u00bb, une collaboration entre le D\u00e9partement d\u2019histoire contemporaine de l\u2019Universit\u00e9 de Fribourg et l\u2019AvaHs, en partenariat avec le Labo urbain de la Ville de Fribourg. Visible \u00e0 l\u2019Atelier durant tout ce mois de mai 2026, en marge des Mondiaux du hockey sur glace qu\u2019accueillait Fribourg (avec Zurich), l\u2019exposition a attir\u00e9 2000 visiteurs\u00b7euses. Pour le lieu, c\u2019est une fr\u00e9quentation sup\u00e9rieure \u00e0 la moyenne, rel\u00e8ve le Service de la culture de la Ville.<\/p>\n<p><strong>Cur\u00e9 No\u00ebl, le \u00abplus grand fan\u00bb<br \/>\n<\/strong>Pour la RTS, ces soir\u00e9es SportVintage permettent une mise en valeur de ses archives sportives. \u00abL\u2019id\u00e9e de venir pr\u00e9senter des archives sur Gott\u00e9ron \u00e0 Fribourg nous trottait dans la t\u00eate depuis un bon moment. Mais on ne s\u2019imaginait pas que l\u2019actualit\u00e9 sportive donnerait autant de couleurs \u00e0 cette soir\u00e9e\u00bb, souligne Sophie Meyer, documentaliste pour RTS archives, faisant r\u00e9f\u00e9rence \u00e0 la r\u00e9cente victoire en finale du championnat de premi\u00e8re ligue nationale du HC Fribourg-Gott\u00e9ron, une premi\u00e8re dans l\u2019histoire du club.<br \/>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div id=\"new-royalslider-173\" class=\"royalSlider new-royalslider-173 rsUni rs-default-template\" style=\"width:100%;height:400px;;\" data-rs-options='{&quot;template&quot;:&quot;default&quot;,&quot;image_generation&quot;:{&quot;imageWidth&quot;:&quot;&quot;,&quot;imageHeight&quot;:&quot;&quot;,&quot;thumbImageWidth&quot;:&quot;&quot;,&quot;thumbImageHeight&quot;:&quot;&quot;},&quot;thumbs&quot;:{&quot;thumbWidth&quot;:96,&quot;thumbHeight&quot;:72},&quot;autoPlay&quot;:{&quot;enabled&quot;:&quot;true&quot;},&quot;fullscreen&quot;:{&quot;enabled&quot;:&quot;true&quot;},&quot;video&quot;:[],&quot;width&quot;:&quot;100%&quot;,&quot;height&quot;:&quot;400px&quot;}'>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Bykov_1992.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Bykov_1992.png\" alt=\"\"\/>\n  \n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Kossmann_2013-1024x492.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Kossmann_2013.png\" alt=\"Kossmann_2013\"\/>\n  \n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Pelletier_1980_02-1024x769.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/Pelletier_1980_02.png\" alt=\"Pelletier_1980_02\"\/>\n  \n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/promotion_1980_02-1024x573.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/promotion_1980_02.png\" alt=\"promotion_1980_02\"\/>\n  \n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/promotion_1980-1024x573.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/promotion_1980.png\" alt=\"promotion_1980\"\/>\n  \n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/titre_2026-1024x666.png\" data-rsBigImg=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2026\/06\/titre_2026.png\" alt=\"titre_2026\"\/>\n  \n  \n  \n<\/div>\n\n<\/div>\n\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p>Dans le sillage de ce succ\u00e8s, le visionnage d\u2019anciennes archives avait donc une saveur particuli\u00e8re. Les s\u00e9quences comportaient des plans in\u00e9dits, tels que la pr\u00e9sentation des nouveaux maillots du club en 1965 ou encore Gabby Marchand \u00e9grenant quelques-uns de ses savoureux souvenirs. Le chansonnier du quartier de l\u2019Auge, berceau historique du club fond\u00e9 en 1937, \u00e9voque notamment le cur\u00e9 Pierre No\u00ebl, figure populaire de la Basse-Ville qui restera probablement dans les annales comme ayant \u00e9t\u00e9 \u00able plus grand fan\u00bb de Gott\u00e9ron.<\/p>\n<p>Nombre d\u2019anecdotes courent sur sa ferveur, les soirs de matchs \u00e0 la patinoire des Augustins. Comme cet \u00e9pisode lors duquel le religieux aurait stopp\u00e9 avec son parapluie un ailier d\u2019Arosa qui d\u00e9bordait le long de la bande. Ou encore la fois o\u00f9 Gabby Marchand se souvient avoir vu ce bon berger des \u00e2mes, choqu\u00e9 par la faute commise par un adversaire de Gott\u00e9ron sur un joueur, sermonner le coupable directement sur le banc des p\u00e9nalit\u00e9s.<\/p>\n<p><strong>Remettre les choses en perspective<br \/>\n<\/strong>Le propos de ce visionnage d\u2019archives, toutefois, d\u00e9passait le simple partage de bons souvenirs. Entre les s\u00e9quences de visionnage, une brochette d\u2019invit\u00e9\u00b7e\u00b7s emmen\u00e9e par la journaliste sportive Marie Ceriani de Radio Fribourg a aid\u00e9 \u00e0 remettre en perspective les diff\u00e9rents aspects de l\u2019histoire du club. Parmi les anciens joueurs, on trouvait Michael Ngoy (de 2005 \u00e0 2016) et Jakob L\u00fcdi. Enfant de la Basse et joueur jusqu\u2019en 1989, ce dernier est l\u2019un des acteurs de la promotion du club en ligue A en 1980.<\/p>\n<p>Am\u00e9lie Jobin, attaquante pour l\u2019\u00e9quipe f\u00e9minine de Gott\u00e9ron (Fribourg-Ladies), a apport\u00e9 son regard sur la situation du hockey f\u00e9minin. A ses c\u00f4t\u00e9s, la journaliste sportive Patricia Morand, ancienne joueuse elle aussi, suit l\u2019\u00e9volution du club pour <em>La Libert\u00e9<\/em> depuis 1988. On trouvait aussi autour de la table le Docteur Philippe Vonnard. Commissaire de l\u2019exposition et sp\u00e9cialiste de l\u2019histoire des sports et des loisirs, le chercheur FNS senior au D\u00e9partement d\u2019histoire contemporaine de l\u2019Unifr a pu donner des \u00e9l\u00e9ments de contexte sur les d\u00e9veloppements du hockey sur glace en Suisse.<\/p>\n<p>Le public a aussi pu compter sur la pr\u00e9sence de Mathieu Boivin-Chouinard, venu en Suisse \u00e0 l\u2019invitation du D\u00e9partement d\u2019histoire contemporaine et du Centre suisse d\u2019\u00e9tudes sur le Qu\u00e9bec et la Francophonie (CEQF), avec le soutien de l\u2019Association internationale des \u00e9tudes qu\u00e9b\u00e9coises. Sp\u00e9cialiste de l\u2019histoire du hockey, notamment sovi\u00e9tique dans sa dimension transnationale, il est doctorant \u00e0 l\u2019Universit\u00e9 du Qu\u00e9bec et enseigne l\u2019histoire au C\u00e9gep Andr\u00e9-Laurendeau \u00e0 Montr\u00e9al. Plus proche de nous, il s\u2019int\u00e9resse aux relations historiques et identitaires du hockey entre le Qu\u00e9bec et l\u2019Arc jurassien.<\/p>\n<p><strong>Un mythe fondateur bien r\u00e9el<br \/>\n<\/strong>Lorsqu\u2019il s\u2019agit du HC Fribourg-Gott\u00e9ron, le Qu\u00e9b\u00e9cois remarque la ferveur de la ville et du canton pour le hockey. Comparaison faite avec le Canada, il observe une diff\u00e9rence dans l\u2019\u00e9mergence de ce lien identitaire. \u00abChez nous, on cultive le mythe d\u2019un hockey n\u00e9 sur les lacs gel\u00e9s des grands espaces nord-am\u00e9ricains. Mais c\u2019est en grande partie construit. En r\u00e9alit\u00e9, au Canada, le hockey est professionnel et commercial d\u00e8s l\u2019origine. A Fribourg, en revanche, le mythe fondateur de ces gamins jouant sur des bassins de pisciculture gel\u00e9s constitue une r\u00e9alit\u00e9 historique\u00bb, souligne-t-il.<\/p>\n<p>Au d\u00e9tour d\u2019une s\u00e9quence d\u2019archives, un de ces anciens \u00abgamins\u00bb du club rappelle ainsi, dans un rire, le reproche que leur faisait le propri\u00e9taire du bassin: \u00abIl fallait laisser des trous dans la glace pour les poissons.\u00bb Ces souvenirs et d\u2019autres ont nourri le fort lien qu\u2019entretient la population avec \u00abson\u00bb club. Pour Jakob L\u00fcdi, cet attachement constitue un fil rouge dans l\u2019histoire de Fribourg-Gott\u00e9ron. \u00abC\u2019est un club qui ne s\u2019ach\u00e8te pas avec de l\u2019argent\u00bb, dit-il.<\/p>\n<p>Philippe Vonnard fait remarquer que cet ancrage local du club s\u2019observe aussi au niveau de l\u2019\u00e9lite dirigeante. \u00abPlusieurs clubs suisses ont \u00e9t\u00e9 administr\u00e9s par des personnes sans lien avec la r\u00e9gion. A Fribourg, les dirigeants \u00e9taient le plus souvent du cru et se sentaient concern\u00e9s par le club et son devenir\u00bb. En outre, rappelle le chercheur, cela n\u2019a pas emp\u00each\u00e9 la dimension commerciale d\u2019intervenir tr\u00e8s t\u00f4t dans la vie de Fribourg-Gott\u00e9ron, comme dans celle d\u2019autres clubs du pays. Ce qui n\u2019est pas un garde-fou: le club ayant connu, dans les ann\u00e9es 1980, des probl\u00e8mes financiers \u00e0 l\u2019instar d\u2019autres clubs romands.<\/p>\n<p><strong>Entra\u00eeneur aujourd\u2019hui, un m\u00e9tier<br \/>\n<\/strong>Une s\u00e9quence s\u2019arr\u00eate sur trois figures qui ont marqu\u00e9 l\u2019histoire du club: Julien Sprunger, le joueur r\u00e9cemment retrait\u00e9 qui a emmen\u00e9 le club \u00e0 la premi\u00e8re place sur le podium helv\u00e9tique; Viatscheslav Bykov, arriv\u00e9 de Russie avec son compatriote Andre\u00ef Khomutov en 1990 au terme d\u2019un d\u00e9marchage audacieux de la part du club dans le contexte de l\u2019\u00e9poque; et Gaston Pelletier (1933-2021), joueur d\u2019origine canadienne et entra\u00eeneur de Fribourg-Gott\u00e9ron entre 1978 et 1982, qui conduira le club en ligue nationale A.<\/p>\n<p>Sur les images d\u2019archives, on voit et on entend ce dernier s\u2019\u00e9nerver contre un joueur sur le banc. Une duret\u00e9 apparente qui cachait une psychologie plut\u00f4t fine. L\u2019entra\u00eeneur, en effet, adaptait son approche \u00e0 la sensibilit\u00e9 des joueurs qu\u2019il avait en face de lui. D\u00e9fenseur sous l\u2019\u00e8re Hans Kossman (entra\u00eeneur principal de 2011 \u00e0 2014), \u00e0 la dure et \u00e0 l\u2019ancienne, l\u2019ancien Dragon Michael Ngoy observe que les entra\u00eeneurs ont d\u00fb s\u2019adapter. \u00abAvec Kossman, on se faisait hurler dessus. Ce qui n\u2019est plus vraiment possible avec les joueurs d\u2019aujourd\u2019hui. Avant, un jeune devait prouver son talent pour avoir du temps de glace. Alors qu\u2019aujourd\u2019hui, le joueur arrive et dit \u00e0 son entra\u00eeneur : \u2039donne-moi du temps de glace et je te montrerai ce que je vaux\u203a. C\u2019est tr\u00e8s diff\u00e9rent.\u00bb<\/p>\n<p>Philippe Vonnard observe pour sa part que le pouvoir est aujourd\u2019hui beaucoup plus dilu\u00e9 entre les diff\u00e9rentes structures \u00e0 l\u2019int\u00e9rieur du club, le staff technique, etc. Les entra\u00eeneurs \u00e9taient-ils plus \u00abdurs\u00bb avant? Difficile \u00e0 dire. \u00abCe qui est s\u00fbr, en revanche, c\u2019est que les formations se sont d\u00e9velopp\u00e9es, tout comme la physiologie et la psychologie du sport, alors que l\u2019usage des r\u00e9seaux sociaux met davantage en lumi\u00e8re certains aspects plus cach\u00e9s. Aujourd\u2019hui, entra\u00eeneur, c\u2019est devenu un m\u00e9tier.\u00bb<\/p>\n<p>Enfin, la soir\u00e9e a aussi permis de souligner quelques enjeux autour du hockey sur glace f\u00e9minin. Ces derni\u00e8res ann\u00e9es, l\u2019\u00e9quipe f\u00e9minine de Fribourg Gott\u00e9ron, les Fribourg-Ladies (premi\u00e8re \u00e9quipe f\u00e9minine de hockey en Suisse cr\u00e9\u00e9e en 1978), progresse. \u00abDepuis trois ans, c\u2019est devenu beaucoup plus int\u00e9ressant\u00bb, rel\u00e8ve Am\u00e9lie Jobin.<\/p>\n<p>Autant d\u2019\u00e9volutions \u00e0 relever, mais le c\u0153ur, lui, ne change pas. \u00abA Fribourg, la connexion avec le club est avant tout \u00e9motionnelle et il faut la ch\u00e9rir, car c\u2019est l\u00e0 qu\u2019on trouve la vraie valeur de cette \u00e9quipe\u00bb, conclut Mathieu Boivin-Chouinard.<\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<span style=\"color: #ff6600;\">__________<\/span><\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<ul>\n<li>Retrouvez notre article sur l&rsquo;exposition <a href=\"https:\/\/www.unifr.ch\/alma-georges\/articles\/2026\/expo-fribourg-gotteron-lhistoire-dune-ferveur\" target=\"_blank\" rel=\"noopener\">\u00abExpo Fribourg Gott\u00e9ron: histoire d&rsquo;une ferveur\u00bb<\/a><\/li>\n<li>Image de une: Match de hockey d&rsquo;enfants du quartier de l&rsquo;Auge devant les Augustins, Fribourg, BCU, cote: <a href=\"https:\/\/www.fr.ch\/bcu\/app\/fonds_photo\/991004818409705509-JATH_25407?f_keyword=hockey%20enfants\" target=\"_blank\" rel=\"noopener\">JATH 25407<\/a><\/li>\n<li>Gallerie photos: \u00a9RTS<\/li>\n<\/ul>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La soir\u00e9e d\u2019archives SportVintage proposait un retour par le son et l\u2019image sur l\u2019histoire du club de hockey fribourgeois. Point d\u2019orgue d\u2019une expo qui a attir\u00e9 2000\u00a0visiteurs et visiteuses durant tout le mois de mai. La temp\u00e9rature est mont\u00e9e d\u2019un cran, ce soir-l\u00e0, sous les poutres du dernier \u00e9tage de l\u2019Atelier \u00e0 Fribourg. Et pas seulement \u00e0 cause de la chaleur ext\u00e9rieure, mais aussi du fait des \u00e9motions ressenties par la centaine de personnes qui s\u2019y \u00e9tait r\u00e9unie. La raison? Le HC Fribourg-Gott\u00e9ron, encore une fois, \u00e9tait au centre de la soir\u00e9e. Ce mercredi 27 mai, le public assistait \u00e0<\/p>\n","protected":false},"author":20,"featured_media":23424,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,75],"tags":[260,1079,128],"class_list":["post-23421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-air","category-a-la-une","tag-histoire","tag-histoire-contemporaine-2","tag-lettres"],"_links":{"self":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/23421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/comments?post=23421"}],"version-history":[{"count":1,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/23421\/revisions"}],"predecessor-version":[{"id":23527,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/23421\/revisions\/23527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media\/23424"}],"wp:attachment":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media?parent=23421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/categories?post=23421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/tags?post=23421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}