{"id":17705,"date":"2023-03-01T09:39:50","date_gmt":"2023-03-01T08:39:50","guid":{"rendered":"https:\/\/www.unifr.ch\/alma-georges?p=17705"},"modified":"2023-03-01T09:40:02","modified_gmt":"2023-03-01T08:40:02","slug":"gare-a-lepuisement-scolaire","status":"publish","type":"post","link":"https:\/\/www.unifr.ch\/alma-georges\/articles\/2023\/gare-a-lepuisement-scolaire?lang=de","title":{"rendered":"Gare \u00e0 l&rsquo;\u00e9puisement scolaire!"},"content":{"rendered":"<h4><strong>Fatigue, lassitude, faible estime de soi? Autant de signes qui pourraient trahir une forme d\u2019\u00e9puisement scolaire. Le Centre de psychologie de la sant\u00e9 de l\u2019Unifr propose des groupes de parole pour aider les \u00e9tudiant\u00b7e\u00b7s \u00e0 se confronter \u00e0 ces sympt\u00f4mes. Les explications de Saba Chopard, assistante dipl\u00f4m\u00e9e.<br \/>\n<\/strong><\/h4>\n<div id=\"attachment_17701\" style=\"width: 160px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2023\/03\/Saba-Chopard.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17701\" class=\"wp-image-17701 size-thumbnail\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2023\/03\/Saba-Chopard-150x150.jpeg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><p id=\"caption-attachment-17701\" class=\"wp-caption-text\">Saba Chopard<\/p><\/div>\n<p><strong>Cette ann\u00e9e, le Centre de psychologie de la sant\u00e9 de l&rsquo;Unifr a mis sur pied des groupes de parole sur la th\u00e9matique de l&rsquo;\u00e9puisement scolaire et du burn-out, pour quelle raison?<br \/>\n<\/strong>Nous sommes en contact \u00e9troit avec le Conseil psychologique aux \u00e9tudiant\u00b7e\u00b7s de l\u2019Universit\u00e9 de Fribourg. Ce dernier a constat\u00e9 une augmentation significative des difficult\u00e9s inh\u00e9rentes \u00e0 l\u2019\u00e9puisement scolaire ainsi qu\u2019au burn-out parmi les \u00e9tudiant\u00b7e\u00b7s qui ont consult\u00e9 l\u2019ann\u00e9e derni\u00e8re. Nous avons aussi pu remarquer, en tant qu\u2019enseignant\u00b7e\u00b7s, une augmentation du niveau du stress parmi les \u00e9tudiant\u00b7e\u00b7s universitaires. C\u2019est la raison pour laquelle nous avons d\u00e9cid\u00e9 de cr\u00e9er ce concept, afin que les personnes qui se trouvent confront\u00e9es \u00e0 des situations pareilles puissent profiter d\u2019un espace d\u2019\u00e9change et de partage bienveillant et s\u00e9curis\u00e9.<\/p>\n<p><strong>Les \u00e9tudiant\u00b7e\u00b7s sont-ils plus sous pression aujourd&rsquo;hui ou plus fragiles?<br \/>\n<\/strong>C\u2019est important de prendre en consid\u00e9ration les deux \u00e9l\u00e9ments. D\u2019un c\u00f4t\u00e9, la soci\u00e9t\u00e9 demande de plus en plus en ce qui concerne la productivit\u00e9 de chacun\u00b7e. Cela nous am\u00e8ne \u00e0 nous sentir souvent sous pression et le risque est de tomber dans une sorte de comp\u00e9tition avec les autres, car \u00abje vais r\u00e9ussir seulement si j\u2019ai tout donn\u00e9 et si j\u2019arrive \u00e0 \u00eatre la ou le meilleur\u00b7e\u00bb, ce qui par cons\u00e9quent cr\u00e9e du stress. De l\u2019autre c\u00f4t\u00e9, il y a s\u00fbrement une fragilisation au niveau de la population g\u00e9n\u00e9rale et de la population estudiantine. Cette vuln\u00e9rabilit\u00e9, qui \u00e9tait peut-\u00eatre d\u00e9j\u00e0 latente, a \u00e9t\u00e9 exacerb\u00e9e surtout suite \u00e0 la p\u00e9riode de la pand\u00e9mie de la covid-19, qui nous a oblig\u00e9\u00b7e\u00b7s \u00e0 changer radicalement nos styles de vie.<\/p>\n<p><strong>Quels sont les signes qui peuvent r\u00e9v\u00e9ler un d\u00e9but d&rsquo;\u00e9puisement scolaire?<br \/>\n<\/strong>Un des sympt\u00f4mes principaux en lien avec l\u2019\u00e9puisement scolaire, c\u2019est de se sentir constamment fatigu\u00e9. Bien s\u00fbr, ce n\u2019est pas le seul signe. Cette probl\u00e9matique inclut g\u00e9n\u00e9ralement trois principales dimensions: l\u2019\u00e9puisement \u00e9motionnel, le cynisme (sentiment de d\u00e9tachement par rapport aux \u00e9tudes ou aux autres) et le faible sentiment d\u2019accomplissement personnel. L\u2019\u00e9puisement scolaire partage beaucoup de similitude avec la d\u00e9pression. La plus grande diff\u00e9rence avec cette derni\u00e8re est que l\u2019\u00e9puisement scolaire est intimement li\u00e9 aux \u00e9tudes. Ce sont ces derni\u00e8res qui causent les sympt\u00f4mes associ\u00e9s \u00e9num\u00e9r\u00e9s ci-dessus.<\/p>\n<p><strong>Quels peuvent \u00eatre les cons\u00e9quences si on ignore le probl\u00e8me?<br \/>\n<\/strong>Plus nous avan\u00e7ons dans le processus d\u2019\u00e9puisement, plus les cons\u00e9quences peuvent devenir lourdes et se chroniciser. Des sympt\u00f4mes cognitifs, telle que la difficult\u00e9 \u00e0 se concentrer, \u00e9motionnels, comme la difficult\u00e9 \u00e0 g\u00e9rer ses \u00e9motions n\u00e9gatives, ainsi que physiques, comme une fatigue persistante et un sommeil perturb\u00e9, peuvent perdurer dans le temps et se g\u00e9n\u00e9raliser aussi \u00e0 d\u2019autres domaines de la vie.<\/p>\n<p><strong>Que peuvent faire les \u00e9tudiant\u00b7e\u00b7s pour \u00e9viter de souffrir d&rsquo;\u00e9puisement scolaire?<br \/>\n<\/strong>En ce qui concerne les facteurs de protection, le soutien social repr\u00e9sente un des facteurs les plus significatifs. Continuer \u00e0 cultiver ses relations et \u00eatre soutenu\u00b7e par notre environnement r\u00e9duiraient le stress face aux \u00e9tudes et, par cons\u00e9quent, rendraient les \u00e9tudiant\u00b7e\u00b7s moins vuln\u00e9rables \u00e0 l\u2019\u00e9puisement scolaire. A c\u00f4t\u00e9 de cela, une bonne hygi\u00e8ne de vie (rythme de vie \u00e9quilibr\u00e9, alimentation, exercice physique etc.), la capacit\u00e9 de prendre soin de soi et de poser ses propres limites ainsi que celle \u00e0 s\u2019auto-observer et \u00e0 s\u2019auto-r\u00e9guler sont des outils qui aident \u00e0 pr\u00e9venir l\u2019\u00e9puisement scolaire.<\/p>\n<p><strong>Vous proposez des groupes de parole sur la th\u00e9matique. Comment se passent ces s\u00e9ances?<br \/>\n<\/strong>Nous proposons quatre s\u00e9ances pendant le semestre de printemps 2023. Chaque s\u00e9ance propose de traiter une th\u00e9matique pr\u00e9cise, tout en laissant aux participant\u00b7e\u00b7s la possibilit\u00e9 de s\u2019exprimer et d\u2019amener les sujets qui leurs paraissent importants. L\u2019id\u00e9e, c\u2019est de proposer des strat\u00e9gies qui peuvent \u00eatre mises en place afin de g\u00e9rer les difficult\u00e9s rencontr\u00e9es. Nous proposons notamment les th\u00e9matiques suivantes: la gestion du temps, la capacit\u00e9 \u00e0 poser ses propres limites, apprendre \u00e0 activer son propre courage et des techniques de relaxation.<\/p>\n<p><strong>Et pour celles et ceux qui auraient peur de parler en public ou souhaiteraient garder l&rsquo;anonymat, y a-t-il d&rsquo;autres options?<br \/>\n<\/strong>Il y a toujours l\u2019option de consulter un\u00b7e psychologue de mani\u00e8re individuelle. Celui ou celle-ci est tenue au secret professionnel. Ce qui est discut\u00e9 en s\u00e9ance reste donc d\u2019ordre priv\u00e9. C\u2019est d\u2019ailleurs important de faire appel \u00e0 un\u00b7e professionnel\u00b7le de la sant\u00e9 si on remarque que la situation devient difficile \u00e0 g\u00e9rer ou si elle commence nous d\u00e9passer.<br \/>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<span style=\"color: #ff6600;\">________<br \/>\n<div class=\"clear\" style=\"height:20px\"><\/div><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/www.unifr.ch\/psycho\/fr\/departement\/personnel\/dept\/people\/73626\/26551\" target=\"_blank\" rel=\"noopener\">Page<\/a> de Saba Chopard<\/li>\n<li><strong><a href=\"https:\/\/www.unifr.ch\/cpe\/fr\/\" target=\"_blank\" rel=\"noopener\">Groupes<\/a><\/strong><a href=\"https:\/\/www.unifr.ch\/cpe\/fr\/\" target=\"_blank\" rel=\"noopener\"> de parole<\/a> autour du burnout:<strong><br \/>\n<\/strong><strong>. \u00ab<\/strong>J&rsquo;apprends \u00e0 me relaxer\u00bb, 25.05.2023, 18h30-20h00<br \/>\n<strong>. \u00ab<\/strong>J&rsquo;active mon courage\u00bb, 27.04.2023, 18h30-20h00<br \/>\n<strong>. \u00ab<\/strong>Je pose mes limites\u00bb, 30.03.2023, 18h30-20h00<\/li>\n<\/ul>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fatigue, lassitude, faible estime de soi? Autant de signes qui pourraient trahir une forme d\u2019\u00e9puisement scolaire. Le Centre de psychologie de la sant\u00e9 de l\u2019Unifr propose des groupes de parole pour aider les \u00e9tudiant\u00b7e\u00b7s \u00e0 se confronter \u00e0 ces sympt\u00f4mes. Les explications de Saba Chopard, assistante dipl\u00f4m\u00e9e. Cette ann\u00e9e, le Centre de psychologie de la sant\u00e9 de l&rsquo;Unifr a mis sur pied des groupes de parole sur la th\u00e9matique de l&rsquo;\u00e9puisement scolaire et du burn-out, pour quelle raison? Nous sommes en contact \u00e9troit avec le Conseil psychologique aux \u00e9tudiant\u00b7e\u00b7s de l\u2019Universit\u00e9 de Fribourg. Ce dernier a constat\u00e9 une augmentation significative<\/p>\n","protected":false},"author":13,"featured_media":17682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113],"tags":[1492,131,1332],"class_list":["post-17705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top","tag-burnout-de","tag-psychologie-de","tag-sante-de"],"_links":{"self":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/comments?post=17705"}],"version-history":[{"count":1,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17705\/revisions"}],"predecessor-version":[{"id":17706,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17705\/revisions\/17706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media\/17682"}],"wp:attachment":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media?parent=17705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/categories?post=17705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/tags?post=17705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}