{"id":17000,"date":"2022-11-22T13:49:13","date_gmt":"2022-11-22T12:49:13","guid":{"rendered":"https:\/\/www.unifr.ch\/alma-georges?p=17000"},"modified":"2022-11-22T13:56:48","modified_gmt":"2022-11-22T12:56:48","slug":"nous-vivons-une-evolution-de-la-lecture","status":"publish","type":"post","link":"https:\/\/www.unifr.ch\/alma-georges\/articles\/2022\/nous-vivons-une-evolution-de-la-lecture","title":{"rendered":"\u00abNous vivons une \u00e9volution de la lecture\u00bb"},"content":{"rendered":"<h4><strong>Durant quatre ans, trois didacticiennes du fran\u00e7ais se sont pench\u00e9es sur un projet de recherche destin\u00e9 \u00e0 valoriser l\u2019enseignement de la litt\u00e9rature num\u00e9rique et des textes num\u00e9riques \u00e0 vis\u00e9e informative. Deux brochures destin\u00e9es aux enseignant\u00b7e\u00b7s du secondaire post-obligatoire ont \u00e9t\u00e9 publi\u00e9es.<\/strong><\/h4>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p>Sylvie Jeanneret (Unifr), Sonya Florey (HEP Vaud) et Violeta Mitrovic (HEP Vaud), toutes trois didacticiennes du fran\u00e7ais, proposent d\u2019int\u00e9grer l\u2019instruction de la litt\u00e9rature num\u00e9rique dans les classes des degr\u00e9s post-obligatoires, toutes fili\u00e8res confondues. Mais cet enseignement n\u2019est pas fr\u00e9quent, les initiatives sont rares et les pistes didactiques quasi inexistantes. Qu\u2019\u00e0 cela ne tienne! Quatre ans plus tard et en collaboration avec des enseignant\u00b7e\u00b7s du secondaire post-obligatoire des Cantons de Fribourg et de Vaud, deux brochures destin\u00e9es \u00e0 l\u2019enseignement sont \u00e9dit\u00e9es. L\u2019une explore les \u0153uvres litt\u00e9raires num\u00e9riques, l\u2019autre se penche davantage sur l\u2019information et la sph\u00e8re m\u00e9diatique.<\/p>\n<p>Nous en parlons avec Sylvie Jeanneret, membre du projet et ma\u00eetresse d\u2019enseignement et de recherche en didactique du fran\u00e7ais \u00e0 l\u2019Unifr.<\/p>\n<p><strong><a href=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2022\/11\/AG_Sylvie_Jeanneret_NB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-17003 alignleft\" src=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2022\/11\/AG_Sylvie_Jeanneret_NB-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2022\/11\/AG_Sylvie_Jeanneret_NB-150x150.jpg 150w, https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2022\/11\/AG_Sylvie_Jeanneret_NB-300x300.jpg 300w, https:\/\/www.unifr.ch\/alma-georges\/wp-content\/uploads\/2022\/11\/AG_Sylvie_Jeanneret_NB.jpg 580w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Comment en vient-on \u00e0 se pencher sur un sujet aussi peu commun qu\u2019est la litt\u00e9rature num\u00e9rique?<br \/>\n<\/strong>Il faut \u00eatre passionn\u00e9, bien s\u00fbr, et avoir une vraie sensibilit\u00e9 pour l\u2019enseignement de la litt\u00e9rature. Nous nous sommes beaucoup int\u00e9ress\u00e9es \u00e0 l\u2019entr\u00e9e du num\u00e9rique dans les classes, surtout au secondaire II, o\u00f9 les injonctions politiques demandent \u00e0 ce que les \u00e9l\u00e8ves d\u00e9veloppent des comp\u00e9tences transversales par rapport au num\u00e9rique. Notre but \u00e9tait de d\u00e9velopper des pistes d\u2019enseignement li\u00e9es \u00e0 la discipline du fran\u00e7ais autour de ce sujet passionnant, mais aussi d\u00e9routant qu\u2019il peut \u00eatre.<\/p>\n<p><strong>D\u00e9routant, pourquoi?<br \/>\n<\/strong>Ce qui est d\u00e9routant avec la litt\u00e9rature num\u00e9rique, c\u2019est la dominance des images, du son et de l\u2019interactivit\u00e9, ce qui lui donne ce c\u00f4t\u00e9 tr\u00e8s multimodal. Il y a \u00e9galement le fait qu\u2019il y a une programmation derri\u00e8re et qu\u2019elle va jouer un r\u00f4le dans le cours du r\u00e9cit, qui se d\u00e9roulera en fonction des choix que l\u2019on peut faire. Ce n\u2019est pas toujours \u00e9vident \u00e0 g\u00e9rer, m\u00eame pour des jeunes qui sont des adeptes de jeux vid\u00e9o et qui, par cons\u00e9quent, comprennent bien l\u2019interactivit\u00e9. Ils peuvent aussi \u00eatre d\u00e9concert\u00e9s par le fait que ce n\u2019est plus tout \u00e0 fait un livre, qui va suivre un r\u00e9cit de mani\u00e8re lin\u00e9aire. On a une entr\u00e9e dans le r\u00e9cit bien diff\u00e9rente de celle sur papier.<\/p>\n<p><strong>Y a-t-il tout de m\u00eame un lien, une continuit\u00e9 entre la litt\u00e9rature classique et num\u00e9rique?<br \/>\n<\/strong>Il y a une continuit\u00e9, oui, bien entendu. Le num\u00e9rique nous permet de red\u00e9finir la caract\u00e9risation de la litt\u00e9rature et ouvre la d\u00e9finition de la litt\u00e9rature classique sur d\u2019autres champs, d\u2019autres objets, d\u2019autres mani\u00e8res de raconter. Le num\u00e9rique est, en fait, un support qui sert \u00e0 explorer le litt\u00e9raire. C\u2019est vrai que cela interroge la place du texte qui n\u2019est plus au centre, mais cela nous permet \u00e9galement de constater les avantages, les points forts et m\u00eame les d\u00e9savantages de la litt\u00e9rature classique.<\/p>\n<p>On peut parler d\u2019\u00e9volution: la litt\u00e9rature n\u2019est plus un univers esth\u00e9tique ferm\u00e9. On explore, on teste; ce n\u2019est pas toujours convainquant, bien s\u00fbr, mais c\u2019est une \u00e9volution quand m\u00eame.<\/p>\n<p><strong>Les brochures publi\u00e9es \u00e9taient-elles pr\u00e9vues au d\u00e9but de la r\u00e9flexion?<br \/>\n<\/strong>Non, pas imm\u00e9diatement. Le projet de base a toujours \u00e9t\u00e9 pens\u00e9 comme une collaboration avec des enseignantes et des enseignants, mais en gardant une couleur intercantonale, c\u2019est-\u00e0-dire en variant les fili\u00e8res, les degr\u00e9s, les \u00e9coles et les professeur\u00b7e\u00b7s, bien s\u00fbr. L\u2019important \u00e9tait d\u2019\u00e9tablir une relation de confiance, d\u2019\u00eatre dans le partage et dans l\u2019ouverture \u00e0 la discussion. C\u2019est par la suite que nous avons cherch\u00e9 \u00e0 communiquer les r\u00e9sultats, \u00e0 mettre les s\u00e9quences et le bilan des enseignant\u00b7e\u00b7s, ainsi que le ressenti des \u00e9l\u00e8ves \u00e0 disposition. Les brochures nous ont paru une mani\u00e8re \u00e9l\u00e9gante d\u2019assembler la th\u00e9orie et la pratique.<\/p>\n<p><strong>Pourquoi est-ce que l\u2019enseignement de la litt\u00e9rature et des textes num\u00e9riques est encore si peu r\u00e9pandu? Est-ce un manque de sources didactiques ou une contre-volont\u00e9 de la part des enseignant\u00b7e\u00b7s?<br \/>\n<\/strong>Je pense qu\u2019il y a deux aspects pour lesquels les \u0153uvres num\u00e9riques ne sont pas plus \u00e9tudi\u00e9es. Le premier est que le num\u00e9rique a toujours \u00e9t\u00e9 consid\u00e9r\u00e9 comme un support, un dispositif efficace pour les activit\u00e9s. Le second est que ce type de litt\u00e9rature n\u2019est pas abord\u00e9 dans les cursus universitaires et n\u2019est, par cons\u00e9quent, pas connu de la part des enseignant\u00b7e\u00b7s. Il y a tr\u00e8s peu de ressources p\u00e9dagogiques en ligne. Les recherches et les diffusions se mettent en place gentiment, mais c\u2019est quand m\u00eame assez r\u00e9cent.<\/p>\n<p>La peur de sortir du cadre, de ne pas ma\u00eetriser assez le sujet, peut effectivement donner de l\u2019appr\u00e9hension aux enseignant\u00b7e\u00b7s. On a aussi une conception de la lecture un peu fig\u00e9e, mais c\u2019est regrettable car personne ne peut se tromper sur un objet d\u2019exploration.<\/p>\n<p><strong>Quels sont les enjeux et l\u2019importance de l\u2019enseignement du num\u00e9rique?<br \/>\n<\/strong>Nous devons montrer aux jeunes que la litt\u00e9rature fait quelque chose avec le num\u00e9rique. C\u2019est un univers o\u00f9 se d\u00e9ploient des \u0153uvres artistiques et c\u2019est \u00e0 nous d\u2019aller les d\u00e9couvrir et les pr\u00e9senter aux \u00e9l\u00e8ves. Ce qui nous int\u00e9resse, c\u2019est de savoir comment former les jeunes \u00e0 leur profession future et d\u00e9velopper leurs comp\u00e9tences de lecture et d\u2019interpr\u00e9tation dans ce contexte de multimodalit\u00e9. Nous avons tout int\u00e9r\u00eat \u00e0 les former pour leur avenir et \u00e0 les rendre conscient\u00b7e\u00b7s que la fa\u00e7on de lire sur du num\u00e9rique implique forc\u00e9ment un changement de rapport avec la lecture. En somme, notre mission est d\u2019apprendre \u00e0 ces \u00e9l\u00e8ves \u00e0 d\u00e9coder ce contexte num\u00e9rique.<\/p>\n<p><strong>Et aux enseignant\u00b7e\u00b7s?<br \/>\n<\/strong>Dans ce cas-l\u00e0, on assiste davantage \u00e0 un mode d\u2019enseignement horizontal plut\u00f4t que transmissif. Les \u00e9l\u00e8ves d\u00e9couvrent les \u0153uvres en m\u00eame temps que leur professeur\u00b7e et les outils d\u2019analyse ne sont pas tout \u00e0 fait les m\u00eames que si l\u2019on travaille sur une \u0153uvre classique sur papier. C\u2019est plut\u00f4t d\u00e9stabilisant, mais aussi tr\u00e8s enrichissant pour les un\u00b7e\u00b7s et les autres. La classe se transforme en un lieu d\u2019exploration et de d\u00e9couverte. Bien s\u00fbr, il est n\u00e9cessaire que l\u2019enseignant\u00b7e ait cette facult\u00e9 d\u2019exploration. Nous nous sommes d\u2019ailleurs rendu compte que cette situation de non-ma\u00eetrise a donn\u00e9 lieu dans les diff\u00e9rentes exp\u00e9rimentations didactiques \u00e0 une pluralit\u00e9 de t\u00e2ches de cr\u00e9ation d\u00e9volues aux \u00e9l\u00e8ves. Comme si le fait d\u2019avoir moins d\u2019\u00e9l\u00e9ments li\u00e9s \u00e0 l\u2019histoire litt\u00e9raire, par exemple, \u00e0 transmettre, laissait de la place \u00e0 d\u2019autres exp\u00e9riences dans la classe.<\/p>\n<p><strong>Pensez-vous que les \u00e9l\u00e8ves ont plus de plaisir \u00e0 lire un texte sous forme num\u00e9rique que sous forme papier?<br \/>\n<\/strong>C\u2019est fascinant de voir comme les \u00e9l\u00e8ves, qui sont pourtant plus sensibles \u00e0 un certain code esth\u00e9tique ou \u00e0 l\u2019interactivit\u00e9, reconnaissent le potentiel de la litt\u00e9rature num\u00e9rique, mais arrivent aussi \u00e0 percevoir les qualit\u00e9s d\u2019un livre papier. L\u2019entr\u00e9e dans la litt\u00e9rature num\u00e9rique implique un changement de rapport affectif avec la lecture: elle est plus complexe et moins \u00e9motive que l\u2019entr\u00e9e dans le livre papier. Les jeunes, qui ont l\u2019habitude des jeux vid\u00e9o ou du multimodal, entreront beaucoup plus facilement dans les \u0153uvres de litt\u00e9rature num\u00e9rique, sans pour autant rejeter l\u2019\u0153uvre sous forme papier. Au final, les avis sont tr\u00e8s nuanc\u00e9s.<\/p>\n<p><strong>Nous n\u2019allons donc pas perdre notre bon vieux papier?<br \/>\n<\/strong>Nous vivons plut\u00f4t une \u00e9volution de la lecture. Les comp\u00e9tences de lecture actuelles sont de plus en plus hybrides et les jeunes vivent dans cette culture de l\u2019hybridation. Cela ne signifie pas la perte du papier, mais la facult\u00e9 de pouvoir lire sur des supports diff\u00e9rents. C\u2019est cette comp\u00e9tence-l\u00e0 que l\u2019on cherche \u00e0 transmettre.<\/p>\n<p><strong>Les r\u00e9sultats sont tr\u00e8s enthousiasmants, quelle suite pourrait \u00eatre envisag\u00e9e \u00e0 cet enseignement?<br \/>\n<\/strong>Je pense qu\u2019il faut pers\u00e9v\u00e9rer, \u00eatre curieux\u00b7euses, \u00eatre explorateurs\u00b7trices de ce qui se fait avec la technologie. L\u2019enjeu du projet \u00e9tait aussi de ne pas laisser tout ce qui se fait avec le num\u00e9rique exclusivement aux disciplines techniques. La litt\u00e9rature num\u00e9rique s\u2019apparente au domaine des arts et les projets interdisciplinaires \u00abfran\u00e7ais\/arts visuels\u00bb pourraient \u00eatre tr\u00e8s int\u00e9ressants, parce qu\u2019il y a cette dimension esth\u00e9tique extr\u00eamement forte. Comme quoi, la litt\u00e9rature n\u2019ob\u00e9it pas \u00e0 des d\u00e9finitions fig\u00e9es. Elle est continuellement en construction, elle est, en quelque sorte, dans l\u2019exploration continue<\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<span style=\"color: #ff6600;\">__________<\/span><\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<ul>\n<li><a href=\"https:\/\/www.unifr.ch\/cerf\/fr\/assets\/public\/pdf\/pages personnelles\/Jeanneret Sylvie\/brochure_web_litterature_numerique.pdf\" target=\"_blank\" rel=\"noopener\">Brochure<\/a> Litt\u00e9rature num\u00e9rique<\/li>\n<li><a href=\"https:\/\/www.unifr.ch\/cerf\/fr\/assets\/public\/pdf\/pages personnelles\/Jeanneret Sylvie\/Brochure_enseigner-textes-numeriques-visee-informative_22.pdf\" target=\"_blank\" rel=\"noopener\">Brochure<\/a> Enseigner les textes num\u00e9riques \u00e0 vis\u00e9e informative<\/li>\n<li><a href=\"https:\/\/www.unifr.ch\/cerf\/fr\/sylvie-jeanneret.html\" target=\"_blank\" rel=\"noopener\">Sylvie Jeanneret<\/a> est ma\u00eetresse d&rsquo;enseignement et de recherche au <a href=\"https:\/\/www.unifr.ch\/cerf\/fr\/\" target=\"_blank\" rel=\"noopener\">Centre d&rsquo;enseignement et de recherche pour la formation \u00e0 l&rsquo;enseignement au secondaire<\/a><\/li>\n<\/ul>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durant quatre ans, trois didacticiennes du fran\u00e7ais se sont pench\u00e9es sur un projet de recherche destin\u00e9 \u00e0 valoriser l\u2019enseignement de la litt\u00e9rature num\u00e9rique et des textes num\u00e9riques \u00e0 vis\u00e9e informative. Deux brochures destin\u00e9es aux enseignant\u00b7e\u00b7s du secondaire post-obligatoire ont \u00e9t\u00e9 publi\u00e9es. Sylvie Jeanneret (Unifr), Sonya Florey (HEP Vaud) et Violeta Mitrovic (HEP Vaud), toutes trois didacticiennes du fran\u00e7ais, proposent d\u2019int\u00e9grer l\u2019instruction de la litt\u00e9rature num\u00e9rique dans les classes des degr\u00e9s post-obligatoires, toutes fili\u00e8res confondues. Mais cet enseignement n\u2019est pas fr\u00e9quent, les initiatives sont rares et les pistes didactiques quasi inexistantes. Qu\u2019\u00e0 cela ne tienne! Quatre ans plus tard et en<\/p>\n","protected":false},"author":68,"featured_media":17002,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,80,75],"tags":[758,128,290,1218],"class_list":["post-17000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enseignement","category-recherche","category-a-la-une","tag-enseignement","tag-lettres","tag-litterature","tag-numerique"],"_links":{"self":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/comments?post=17000"}],"version-history":[{"count":1,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17000\/revisions"}],"predecessor-version":[{"id":17007,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/17000\/revisions\/17007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media\/17002"}],"wp:attachment":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media?parent=17000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/categories?post=17000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/tags?post=17000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}