{"id":10666,"date":"2020-03-30T10:06:55","date_gmt":"2020-03-30T09:06:55","guid":{"rendered":"https:\/\/www3.unifr.ch\/alma-georges?p=10666"},"modified":"2020-03-30T14:20:45","modified_gmt":"2020-03-30T13:20:45","slug":"lanalyse-de-donnees-est-devenue-incontournable-dans-leconomie","status":"publish","type":"post","link":"https:\/\/www.unifr.ch\/alma-georges\/articles\/2020\/lanalyse-de-donnees-est-devenue-incontournable-dans-leconomie","title":{"rendered":"\u00abL\u2019analyse de donn\u00e9es est devenue incontournable dans l\u2019\u00e9conomie\u00bb"},"content":{"rendered":"<h4><strong>Alors que de plus en plus de donn\u00e9es sont disponibles sur le comportement des consommateurs et des entreprises, l\u2019analyse de ces donn\u00e9es est devenue un enjeu majeur de l\u2019\u00e9conomie. Dans ce contexte, l\u2019Unifr lance un master in\u00e9dit en data analytics &amp; economics. Lever de voile en compagnie de son pilote Berno Buechel et de son premier \u00e9tudiant, Yann Costa.<\/strong><\/h4>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p><strong>Pourquoi avoir mis sur pied un cursus de master combinant l\u2019analyse de donn\u00e9es aux th\u00e9ories \u00e9conomiques d\u2019analyse du march\u00e9 et des entreprises?<br \/>\n<\/strong><em>Berno Buechel:<\/em> Le monde est en plein changement. Deux grands <em>trends<\/em> se d\u00e9marquent. D\u2019une part, de plus en plus de donn\u00e9es sont disponibles sur le comportement des consommateurs et des entreprises, et il existe des techniques de plus en plus perfectionn\u00e9es pour analyser ces donn\u00e9es. D\u2019autre part, les structures de march\u00e9 connaissent une mutation radicale en raison du nouveau r\u00f4le des plateformes en ligne. Ce double d\u00e9veloppement a boulevers\u00e9 la fa\u00e7on dont fonctionnent de nombreuses entreprises. Prenez l\u2019exemple des plateformes de r\u00e9servation. Elles modifient \u00e0 la fois notre fa\u00e7on de pr\u00e9parer nos vacances et la fa\u00e7on dont les \u00e9tablissements touristiques gagnent de l\u2019argent. Or, peu de professionnels sont capables de comprendre les deux aspects sous-jacents, l\u2019analyse de donn\u00e9es et l\u2019\u00e9conomie. D\u2019o\u00f9 ce projet de Master en data analytics &amp; economics.<\/p>\n<p><strong>G\u00e9n\u00e9ralement, ces deux branches sont donc cloisonn\u00e9es?<br \/>\n<\/strong><em>Berno Buechel<\/em>: Pas compl\u00e8tement. Parmi les \u00e9conomistes, il y a certes une tradition d\u2019analyse de donn\u00e9es. Mais ce qui manque \u00e0 ces \u00e9conomistes, c\u2019est la facult\u00e9 de programmer eux-m\u00eames et de faire face \u00e0 des quantit\u00e9s de donn\u00e9es beaucoup plus importantes que celles auxquelles ils sont habitu\u00e9s. A l\u2019inverse, les sp\u00e9cialistes \u00e9manant de l\u2019informatique et de la <em>data science<\/em> manquent souvent de connaissances \u00e9conomiques. La combinaison des deux est rare. Or, du c\u00f4t\u00e9 des entreprises, on observe une demande en ce sens; elles engagent, certes, les deux types d\u2019experts, mais ont parfois de la peine \u00e0 les faire cohabiter.<\/p>\n<p><strong>Comment le cursus a-t-il \u00e9t\u00e9 \u00e9labor\u00e9?<br \/>\n<\/strong><em>Berno Buechel<\/em>: L\u2019inspiration principale est venue de plusieurs universit\u00e9s am\u00e9ricaines de renom. Constatant qu\u2019aucun programme similaire n\u2019existait en Suisse, des membres du D\u00e9partement d\u2019\u00e9conomie politique de l\u2019Unifr sont all\u00e9s trouver leurs coll\u00e8gues du D\u00e9partement d\u2019informatique. Rappelons qu\u2019\u00e0 Fribourg, nous avons la chance de pouvoir compter sur une grande expertise dans les deux domaines. A commenc\u00e9 un processus d\u2019environ deux ans durant lequel le programme des cours a \u00e9t\u00e9 \u00e9labor\u00e9.<\/p>\n<p><strong>En Suisse, l\u2019association entre <em>data analytics<\/em> et <em>economics<\/em> est donc une premi\u00e8re<br \/>\n<\/strong><em>Berno Buechel<\/em>: En effet! D\u2019autres \u00e9tablissements offrent des cursus alliant analyse de donn\u00e9es et perspective manag\u00e9riale. Dans notre cas, l\u2019angle est diff\u00e9rent et in\u00e9dit: il s\u2019agit d\u2019une perspective \u00ab\u00e9conomie de march\u00e9 et des organisations\u00bb.<\/p>\n<p><strong>Pouvez-vous donner quelques informations pratiques sur ce master?<br \/>\n<\/strong><em>Berno Buechel<\/em>: Le Master en data analytics &amp; economics de l\u2019Unifr d\u00e9marrera en septembre 2020 avec un premier groupe d\u2019\u00e9tudiant\u00b7e\u00b7s, comprenant Yann Costa. Divers <em>backgrounds<\/em> donnent acc\u00e8s \u00e0 cette formation, dont les deux voies naturelles, \u00e0 savoir les bachelors en \u00e9conomie et en informatique. Les \u00e9tudiant\u00b7e\u00b7s issus de l\u2019une de ces disciplines devront logiquement travailler un peu plus intensivement dans l\u2019autre. Le crit\u00e8re d\u2019admission principal est la motivation \u00e0 apprendre; nul besoin d\u2019\u00eatre quelqu\u2019un qui bidouille avec des ordinateurs dans son garage depuis sa plus tendre enfance\u2026 (<em>Rires)<\/em><\/p>\n<p><strong>Yann Costa, vous \u00eates le premier \u00e9tudiant \u00e0 vous \u00eatre inscrit au master en data analytics &amp; economics; quel est votre profil?<br \/>\n<\/strong><em>Yann Costa:<\/em> J\u2019ai termin\u00e9 en 2019 un Bachelor en gestion d\u2019entreprise \u00e0 l\u2019Unifr. Parall\u00e8lement, je me suis toujours int\u00e9ress\u00e9 aux nouvelles technologies et aux entreprises actives dans ce secteur. Mais je n\u2019ai jamais eu envie de me sp\u00e9cialiser en informatique, car je suis plus dou\u00e9 derri\u00e8re un ordinateur que le nez dedans. <em>(Rires)<\/em> Ce sont plut\u00f4t les mod\u00e8les d\u2019affaires des entreprises, ainsi que les possibilit\u00e9s offertes par la technologie en mati\u00e8re de nouvelles solutions, qui me passionnent. Ce master constitue, \u00e0 mon avis, la formation id\u00e9ale pour quelqu\u2019un qui souhaiterait travailler dans la partie strat\u00e9gique et op\u00e9rationnelle d\u2019une entreprise technologique.<\/p>\n<p><strong>D\u2019o\u00f9 est parti votre int\u00e9r\u00eat pour cette formation?<br \/>\n<\/strong><em>Yann Costa<\/em>: J\u2019ai lu un article de la soci\u00e9t\u00e9 de conseil McKinsey consacr\u00e9 \u00e0 un nouveau m\u00e9tier \u00e9mergent, \u00e0 savoir <em>data translator<\/em> (traducteur de donn\u00e9es). L\u2019article estimait \u00e0 4 millions le nombre d\u2019emplois cr\u00e9\u00e9s d\u2019ici 2026 sur le march\u00e9 am\u00e9ricain, en expliquant que cette tendance haussi\u00e8re allait aussi concerner l\u2019Europe. Quand j\u2019ai vu que l\u2019offre de l\u2019Unifr correspondait exactement \u00e0 ce m\u00e9tier, je n\u2019ai pas h\u00e9sit\u00e9. D\u2019autant que la brochette d\u2019enseignant\u00b7e\u00b7s est tr\u00e8s all\u00e9chante. A mon avis, d\u2019ici 10 ans, travailler dans l\u2019\u00e9conomie sans connaissances dans l\u2019analyse de donn\u00e9es sera l\u2019\u00e9quivalent de ne pas savoir utiliser une bo\u00eete mail en 2010.<\/p>\n<p><strong>Quel serait pour vous l\u2019emploi id\u00e9al apr\u00e8s votre master?<br \/>\n<\/strong><em>Yann Costa<\/em>: Justement faire le pont entre deux \u00e9quipes et transformer les donn\u00e9es d\u2019une entreprise en solutions utiles, histoire qu\u2019elles ne dorment pas dans un ordinateur. D\u2019autant plus si ces solutions tendent vers le d\u00e9veloppement durable.<\/p>\n<p><em>Berno Buechel<\/em>: La motivation du programme \u00e9tait justement de se demander quel est le besoin des entreprises. Attention, cela ne se limite pas aux grandes entreprises! Pensez \u00e0 une structure telle que Comparis. En raison de son action, les grandes compagnies d\u2019assurance sont oblig\u00e9es de changer leurs pratiques. Notre master ne s\u2019adresse donc de loin pas seulement aux \u00e9tudiant\u00b7e\u00b7s qui r\u00eavent d\u2019int\u00e9grer des multinationales technologiques.<\/p>\n<p><em>Yann Costa<\/em>: Je pourrais comprendre qu\u2019un \u00e9tudiant h\u00e9site \u00e0 choisir ce master par peur de contribuer \u00e0 faire gagner encore plus d\u2019argent \u00e0 des<em> big compagnies.<\/em> J\u2019ai envie de leur dire: \u00e0 l\u2019inverse, c\u2019est une raison de plus pour se lancer! En effet, si elles veulent avoir une chance de concurrencer les grands groupes, les PME doivent \u00eatre en mesure de comprendre et d\u2019exploiter le potentiel des donn\u00e9es.<\/p>\n<p><strong>Peut-on envisager que certain\u00b7e\u00b7s futur\u00b7e\u00b7s titulaires du master travaillent pour des ONG ou pour le service public?<br \/>\n<\/strong><em>Berno Buechel<\/em>: Absolument! Dans le cas du service public, on peut notamment citer les autorit\u00e9s de la concurrence. Car qui dit changement du march\u00e9, dit changement de la r\u00e9gulation du march\u00e9. Est-il acceptable qu\u2019une plateforme de r\u00e9servation touristique force les h\u00f4tels \u00e0 offrir leur meilleur tarif en ligne?<\/p>\n<p><strong>Reste qu\u2019\u00e0 l\u2019\u00e8re du <em>big data<\/em>, la question de la protection des donn\u00e9es est sur toutes les l\u00e8vres. Allez-vous th\u00e9matiser cet aspect?<br \/>\n<\/strong><em>Berno Buechel<\/em>: Oui, il est tr\u00e8s important de rappeler que les donn\u00e9es ne peuvent pas \u00eatre trait\u00e9es \u00e0 la l\u00e9g\u00e8re. Il y a des questions \u00e9thiques, juridiques et techniques li\u00e9es. Prenez le cas d\u2019un h\u00f4pital: comment utiliser les donn\u00e9es de patient\u00b7e\u00b7s pour faire avancer la recherche sans pour autant en apprendre trop sur ces patient\u00b7e\u00b7s? Il existe justement de nouvelles solutions technologiques int\u00e9ressantes qui peuvent aider \u00e0 r\u00e9soudre ce paradoxe.<\/p>\n<p><strong>On associe encore souvent technologie et masculinit\u00e9. Comment faire en sorte d\u2019assurer la mixit\u00e9 des participant\u00b7e\u00b7s au master?<br \/>\n<\/strong><em>Berno Buechel<\/em>: Il n\u2019y a aucune raison pour laquelle les hommes devraient \u00eatre davantage attir\u00e9s par la technologie! Nous souhaitons lutter contre ce st\u00e9r\u00e9otype et encourageons vivement les femmes \u00e0 s\u2019inscrire au master. A condition bien s\u00fbr qu\u2019elles soient int\u00e9ress\u00e9es et motiv\u00e9es. C\u2019est d\u2019ailleurs pourquoi nous avons choisi de faire figurer une femme plut\u00f4t qu\u2019un homme sur notre flyer de pr\u00e9sentation.<\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<p><span style=\"color: #ff6600;\">__________<\/span><\/p>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<ul>\n<li><a href=\"https:\/\/www3.unifr.ch\/amabe\/fr\/chaire\/team\/prof.html\" target=\"_blank\" rel=\"noopener noreferrer\">Berno Buechel <\/a>est professeur d\u2019\u00e9conomie \u00e0 l\u2019Unifr. Il est responsable du nouveau Master en data analytics &amp; economics, qui d\u00e9marrera en septembre 2020.<\/li>\n<li><a href=\"https:\/\/www3.unifr.ch\/directory\/de\/people\/183307\/85d8b\" target=\"_blank\" rel=\"noopener noreferrer\">Yann Costa<\/a> est titulaire d\u2019un bachelor en gestion d\u2019entreprise de l\u2019Unifr. Il est le premier \u00e9tudiant \u00e0 s\u2019\u00eatre inscrit au nouveau Master en data analytics &amp; economics.<\/li>\n<li>En savoir plus sur le <a href=\"http:\/\/www3.unifr.ch\/ses\/web2015\/index.php?page=description-ma-en-data-analytics-Economics\" target=\"_blank\" rel=\"noopener noreferrer\">Master en data analytics &amp; economics<\/a><\/li>\n<\/ul>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n<div class=\"clear\" style=\"height:20px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alors que de plus en plus de donn\u00e9es sont disponibles sur le comportement des consommateurs et des entreprises, l\u2019analyse de ces donn\u00e9es est devenue un enjeu majeur de l\u2019\u00e9conomie. Dans ce contexte, l\u2019Unifr lance un master in\u00e9dit en data analytics &amp; economics. Lever de voile en compagnie de son pilote Berno Buechel et de son premier \u00e9tudiant, Yann Costa. Pourquoi avoir mis sur pied un cursus de master combinant l\u2019analyse de donn\u00e9es aux th\u00e9ories \u00e9conomiques d\u2019analyse du march\u00e9 et des entreprises? Berno Buechel: Le monde est en plein changement. Deux grands trends se d\u00e9marquent. D\u2019une part, de plus en plus<\/p>\n","protected":false},"author":53,"featured_media":10672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,75],"tags":[237,151,340],"_links":{"self":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/10666"}],"collection":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/comments?post=10666"}],"version-history":[{"count":5,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/10666\/revisions"}],"predecessor-version":[{"id":10675,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/posts\/10666\/revisions\/10675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media\/10672"}],"wp:attachment":[{"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/media?parent=10666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/categories?post=10666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unifr.ch\/alma-georges\/wp-json\/wp\/v2\/tags?post=10666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}